{"id":34807,"date":"2024-02-15T17:15:58","date_gmt":"2024-02-15T16:20:16","guid":{"rendered":"https:\/\/bigli21.it\/?post_type=product&#038;p=34807"},"modified":"2024-02-16T14:42:45","modified_gmt":"2024-02-16T13:42:45","slug":"necklace-kilim-black-white-magnetic-closure-white-crystals-copia","status":"publish","type":"product","link":"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/","title":{"rendered":"Necklace Kilim Black &#038; White Magnetic Closure Grey Crystals"},"content":{"rendered":"<p>Necklace Kilim Black &amp; White Magnetic Closure Grey Crystals 40 cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Necklace Kilim Black &amp; White Magnetic Closure Grey Crystals 40 cm<\/p>\n","protected":false},"featured_media":33218,"template":"","meta":[],"product_brand":[],"product_cat":[949,951],"product_tag":[618],"class_list":{"0":"post-34807","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-necklaces","7":"product_cat-necklaces-kilim-collection-en","8":"product_tag-pearl-gray","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"supplier_id":null,"supplier_sku":"","barcode":null,"atum_controlled":true,"out_stock_date":null,"out_stock_threshold":null,"inheritable":false,"inbound_stock":null,"stock_on_hold":null,"sold_today":null,"sales_last_days":null,"reserved_stock":null,"customer_returns":null,"warehouse_damage":null,"lost_in_post":null,"other_logs":null,"out_stock_days":null,"lost_sales":null,"has_location":false,"update_date":"2024-02-19T14:56:32","atum_locations":[],"atum_stock_status":"instock","restock_status":false,"low_stock_amount":"","sales_update_date":null,"calc_backorders":null,"linked_bom":[{"bom_id":15580,"bom_type":"product_part","qty":2,"measure_unit":null},{"bom_id":15315,"bom_type":"product_part","qty":1,"measure_unit":null}],"sync_purchase_price":false,"bom_sellable":null,"minimum_threshold":null,"available_to_purchase":null,"selling_priority":null,"calculated_stock":null,"is_bom":false,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Necklace Kilim Black &amp; White Magnetic Closure Grey Crystals | Bigli21<\/title>\n<meta name=\"description\" content=\"Bigli21 \u00e8 un marchio di gioielli nato tra i vicoli del quadrilatero della moda, respirando l\u2019energia e la creativit\u00e0 metropolitana milanese unendosi in un gioco di stili e colori dai sapori internazionali.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Necklace Kilim Black &amp; White Magnetic Closure Grey Crystals | Bigli21\" \/>\n<meta property=\"og:description\" content=\"Bigli21 \u00e8 un marchio di gioielli nato tra i vicoli del quadrilatero della moda, respirando l\u2019energia e la creativit\u00e0 metropolitana milanese unendosi in un gioco di stili e colori dai sapori internazionali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/\" \/>\n<meta property=\"og:site_name\" content=\"Bigli21\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-16T13:42:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bigli21.it\/wp-content\/uploads\/2023\/10\/KILIM-BW-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1905\" \/>\n\t<meta property=\"og:image:height\" content=\"1429\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/\",\"url\":\"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/\",\"name\":\"Necklace Kilim Black & White Magnetic Closure Grey Crystals | Bigli21\",\"isPartOf\":{\"@id\":\"https:\/\/bigli21.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bigli21.it\/wp-content\/uploads\/2023\/10\/KILIM-BW-5.png\",\"datePublished\":\"2024-02-15T16:20:16+00:00\",\"dateModified\":\"2024-02-16T13:42:45+00:00\",\"description\":\"Bigli21 \u00e8 un marchio di gioielli nato tra i vicoli del quadrilatero della moda, respirando l\u2019energia e la creativit\u00e0 metropolitana milanese unendosi in un gioco di stili e colori dai sapori internazionali.\",\"breadcrumb\":{\"@id\":\"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/#primaryimage\",\"url\":\"https:\/\/bigli21.it\/wp-content\/uploads\/2023\/10\/KILIM-BW-5.png\",\"contentUrl\":\"https:\/\/bigli21.it\/wp-content\/uploads\/2023\/10\/KILIM-BW-5.png\",\"width\":1905,\"height\":1429},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bigli21.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/bigli21.it\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Necklace Kilim Black &#038; White Magnetic Closure Grey Crystals\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bigli21.it\/#website\",\"url\":\"https:\/\/bigli21.it\/\",\"name\":\"Bigli21\",\"description\":\"Braccialetti personalizzati\",\"publisher\":{\"@id\":\"https:\/\/bigli21.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bigli21.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bigli21.it\/#organization\",\"name\":\"Bigli 21\",\"url\":\"https:\/\/bigli21.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/bigli21.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bigli21.it\/wp-content\/uploads\/2023\/11\/logo400.jpg\",\"contentUrl\":\"https:\/\/bigli21.it\/wp-content\/uploads\/2023\/11\/logo400.jpg\",\"width\":400,\"height\":167,\"caption\":\"Bigli 21\"},\"image\":{\"@id\":\"https:\/\/bigli21.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Necklace Kilim Black & White Magnetic Closure Grey Crystals | Bigli21","description":"Bigli21 \u00e8 un marchio di gioielli nato tra i vicoli del quadrilatero della moda, respirando l\u2019energia e la creativit\u00e0 metropolitana milanese unendosi in un gioco di stili e colori dai sapori internazionali.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/","og_locale":"en_US","og_type":"article","og_title":"Necklace Kilim Black & White Magnetic Closure Grey Crystals | Bigli21","og_description":"Bigli21 \u00e8 un marchio di gioielli nato tra i vicoli del quadrilatero della moda, respirando l\u2019energia e la creativit\u00e0 metropolitana milanese unendosi in un gioco di stili e colori dai sapori internazionali.","og_url":"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/","og_site_name":"Bigli21","article_modified_time":"2024-02-16T13:42:45+00:00","og_image":[{"width":1905,"height":1429,"url":"https:\/\/bigli21.it\/wp-content\/uploads\/2023\/10\/KILIM-BW-5.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/","url":"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/","name":"Necklace Kilim Black & White Magnetic Closure Grey Crystals | Bigli21","isPartOf":{"@id":"https:\/\/bigli21.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/#primaryimage"},"image":{"@id":"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/#primaryimage"},"thumbnailUrl":"https:\/\/bigli21.it\/wp-content\/uploads\/2023\/10\/KILIM-BW-5.png","datePublished":"2024-02-15T16:20:16+00:00","dateModified":"2024-02-16T13:42:45+00:00","description":"Bigli21 \u00e8 un marchio di gioielli nato tra i vicoli del quadrilatero della moda, respirando l\u2019energia e la creativit\u00e0 metropolitana milanese unendosi in un gioco di stili e colori dai sapori internazionali.","breadcrumb":{"@id":"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/#primaryimage","url":"https:\/\/bigli21.it\/wp-content\/uploads\/2023\/10\/KILIM-BW-5.png","contentUrl":"https:\/\/bigli21.it\/wp-content\/uploads\/2023\/10\/KILIM-BW-5.png","width":1905,"height":1429},{"@type":"BreadcrumbList","@id":"https:\/\/bigli21.it\/en\/product\/necklace-kilim-black-white-magnetic-closure-white-crystals-copia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bigli21.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/bigli21.it\/shop\/"},{"@type":"ListItem","position":3,"name":"Necklace Kilim Black &#038; White Magnetic Closure Grey Crystals"}]},{"@type":"WebSite","@id":"https:\/\/bigli21.it\/#website","url":"https:\/\/bigli21.it\/","name":"Bigli21","description":"Braccialetti personalizzati","publisher":{"@id":"https:\/\/bigli21.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bigli21.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bigli21.it\/#organization","name":"Bigli 21","url":"https:\/\/bigli21.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bigli21.it\/#\/schema\/logo\/image\/","url":"https:\/\/bigli21.it\/wp-content\/uploads\/2023\/11\/logo400.jpg","contentUrl":"https:\/\/bigli21.it\/wp-content\/uploads\/2023\/11\/logo400.jpg","width":400,"height":167,"caption":"Bigli 21"},"image":{"@id":"https:\/\/bigli21.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bigli21.it\/en\/wp-json\/wp\/v2\/product\/34807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bigli21.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bigli21.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bigli21.it\/en\/wp-json\/wp\/v2\/media\/33218"}],"wp:attachment":[{"href":"https:\/\/bigli21.it\/en\/wp-json\/wp\/v2\/media?parent=34807"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bigli21.it\/en\/wp-json\/wp\/v2\/product_brand?post=34807"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bigli21.it\/en\/wp-json\/wp\/v2\/product_cat?post=34807"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bigli21.it\/en\/wp-json\/wp\/v2\/product_tag?post=34807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}